{"id":6434,"date":"2019-10-16T12:26:15","date_gmt":"2019-10-16T12:26:15","guid":{"rendered":"https:\/\/greenglow.co\/product\/nozzle-for-pop-up-with-filter-15an\/"},"modified":"2025-10-04T12:16:11","modified_gmt":"2025-10-04T12:16:11","slug":"nozzle-for-pop-up-with-filter-15an","status":"publish","type":"product","link":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/","title":{"rendered":"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 &#8211; ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 )"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0642\u0637\u0639\u0629 \u0641\u064a \u0627\u0644\u0643\u064a\u0633: 25 \u0642\u0637\u0639\u0629<\/p>\n","protected":false},"featured_media":467252,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[443],"product_tag":[],"class_list":["post-6434","product","type-product","status-publish","has-post-thumbnail","product_cat-agriculture-sprinkler-system","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 - ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 ) - \u062c\u0631\u064a\u0646 \u062c\u0644\u0648<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 - ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 )\" \/>\n<meta property=\"og:description\" content=\"\u0642\u0637\u0639\u0629 \u0641\u064a \u0627\u0644\u0643\u064a\u0633: 25 \u0642\u0637\u0639\u0629\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/\" \/>\n<meta property=\"og:site_name\" content=\"\u062c\u0631\u064a\u0646 \u062c\u0644\u0648\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GREENGLOWUAE\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-04T12:16:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2019\/10\/nozzle_with_filter.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GREENGLOWUAE\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/\",\"url\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/\",\"name\":\"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 - ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 ) - \u062c\u0631\u064a\u0646 \u062c\u0644\u0648\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.greenglow.ae\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/nozzle_with_filter.webp\",\"datePublished\":\"2019-10-16T12:26:15+00:00\",\"dateModified\":\"2025-10-04T12:16:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.greenglow.ae\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/nozzle_with_filter.webp\",\"contentUrl\":\"https:\\\/\\\/www.greenglow.ae\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/nozzle_with_filter.webp\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/product\\\/nozzle-for-pop-up-with-filter-15an\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0645\u062a\u062c\u0631\",\"item\":\"https:\\\/\\\/www.greenglow.ae\\\/ar\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 &#8211; ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 )\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/#website\",\"url\":\"https:\\\/\\\/www.greenglow.ae\\\/\",\"name\":\"GREEN GLOW UAE\",\"description\":\"\u0635\u0646\u0627\u0639\u0629 \u0648\u062a\u0648\u0632\u064a\u0639 \u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0631\u064a \u0627\u0644\u0632\u0631\u0627\u0639\u064a\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.greenglow.ae\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/#organization\",\"name\":\"Green Glow General Trading Llc\",\"url\":\"https:\\\/\\\/www.greenglow.ae\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.greenglow.ae\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-greenglow-fav.webp\",\"contentUrl\":\"https:\\\/\\\/www.greenglow.ae\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-greenglow-fav.webp\",\"width\":512,\"height\":512,\"caption\":\"Green Glow General Trading Llc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.greenglow.ae\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GREENGLOWUAE\\\/\",\"https:\\\/\\\/x.com\\\/GREENGLOWUAE\",\"https:\\\/\\\/www.instagram.com\\\/greenglowuae\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/GREENGLOWUAE\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyr-NV21QFBiUcyo72N7MeA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 - ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 ) - \u062c\u0631\u064a\u0646 \u062c\u0644\u0648","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 - ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 )","og_description":"\u0642\u0637\u0639\u0629 \u0641\u064a \u0627\u0644\u0643\u064a\u0633: 25 \u0642\u0637\u0639\u0629","og_url":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/","og_site_name":"\u062c\u0631\u064a\u0646 \u062c\u0644\u0648","article_publisher":"https:\/\/www.facebook.com\/GREENGLOWUAE\/","article_modified_time":"2025-10-04T12:16:11+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2019\/10\/nozzle_with_filter.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@GREENGLOWUAE","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"1 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/","url":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/","name":"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 - ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 ) - \u062c\u0631\u064a\u0646 \u062c\u0644\u0648","isPartOf":{"@id":"https:\/\/www.greenglow.ae\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/#primaryimage"},"image":{"@id":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2019\/10\/nozzle_with_filter.webp","datePublished":"2019-10-16T12:26:15+00:00","dateModified":"2025-10-04T12:16:11+00:00","breadcrumb":{"@id":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/#primaryimage","url":"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2019\/10\/nozzle_with_filter.webp","contentUrl":"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2019\/10\/nozzle_with_filter.webp","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.greenglow.ae\/ar\/product\/nozzle-for-pop-up-with-filter-15an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.greenglow.ae\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0645\u062a\u062c\u0631","item":"https:\/\/www.greenglow.ae\/ar\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0646\u0648\u0632\u0644 \u0628\u0648\u0628 \u0627\u0628 15 &#8211; ( \u0643\u064a\u0633 \u0645\u0646 25 \u0642\u0637\u0639\u0629 )"}]},{"@type":"WebSite","@id":"https:\/\/www.greenglow.ae\/#website","url":"https:\/\/www.greenglow.ae\/","name":"GREEN GLOW UAE","description":"\u0635\u0646\u0627\u0639\u0629 \u0648\u062a\u0648\u0632\u064a\u0639 \u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0631\u064a \u0627\u0644\u0632\u0631\u0627\u0639\u064a","publisher":{"@id":"https:\/\/www.greenglow.ae\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.greenglow.ae\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.greenglow.ae\/#organization","name":"Green Glow General Trading Llc","url":"https:\/\/www.greenglow.ae\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.greenglow.ae\/#\/schema\/logo\/image\/","url":"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2025\/10\/cropped-greenglow-fav.webp","contentUrl":"https:\/\/www.greenglow.ae\/wp-content\/uploads\/2025\/10\/cropped-greenglow-fav.webp","width":512,"height":512,"caption":"Green Glow General Trading Llc"},"image":{"@id":"https:\/\/www.greenglow.ae\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GREENGLOWUAE\/","https:\/\/x.com\/GREENGLOWUAE","https:\/\/www.instagram.com\/greenglowuae\/","https:\/\/www.pinterest.com\/GREENGLOWUAE\/","https:\/\/www.youtube.com\/channel\/UCyr-NV21QFBiUcyo72N7MeA"]}]}},"_links":{"self":[{"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/product\/6434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/comments?post=6434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/media\/467252"}],"wp:attachment":[{"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/media?parent=6434"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/product_brand?post=6434"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/product_cat?post=6434"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.greenglow.ae\/ar\/wp-json\/wp\/v2\/product_tag?post=6434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}